{"id":3618,"count":18,"description":"","link":"https:\/\/www.anadess.com\/blog\/category\/livres\/adp4-tome1\/","name":"ADP4-Tome1","slug":"adp4-tome1","taxonomy":"category","parent":3605,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives des ADP4-Tome1 -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.anadess.com\/blog\/category\/livres\/adp4-tome1\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des ADP4-Tome1 -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.anadess.com\/blog\/category\/livres\/adp4-tome1\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/category\\\/livres\\\/adp4-tome1\\\/\",\"url\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/category\\\/livres\\\/adp4-tome1\\\/\",\"name\":\"Archives des ADP4-Tome1 -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/category\\\/livres\\\/adp4-tome1\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/category\\\/livres\\\/adp4-tome1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Livres\",\"item\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/category\\\/livres\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ADP4-Tome1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des ADP4-Tome1 -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.anadess.com\/blog\/category\/livres\/adp4-tome1\/","og_locale":"fr_FR","og_type":"article","og_title":"Archives des ADP4-Tome1 -","og_url":"https:\/\/www.anadess.com\/blog\/category\/livres\/adp4-tome1\/","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.anadess.com\/blog\/category\/livres\/adp4-tome1\/","url":"https:\/\/www.anadess.com\/blog\/category\/livres\/adp4-tome1\/","name":"Archives des ADP4-Tome1 -","isPartOf":{"@id":"https:\/\/www.anadess.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.anadess.com\/blog\/category\/livres\/adp4-tome1\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.anadess.com\/blog\/category\/livres\/adp4-tome1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.anadess.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Livres","item":"https:\/\/www.anadess.com\/blog\/category\/livres\/"},{"@type":"ListItem","position":3,"name":"ADP4-Tome1"}]},{"@type":"WebSite","@id":"https:\/\/www.anadess.com\/blog\/#website","url":"https:\/\/www.anadess.com\/blog\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.anadess.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.anadess.com\/blog\/wp-json\/wp\/v2\/categories\/3618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.anadess.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.anadess.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.anadess.com\/blog\/wp-json\/wp\/v2\/categories\/3605"}],"wp:post_type":[{"href":"https:\/\/www.anadess.com\/blog\/wp-json\/wp\/v2\/posts?categories=3618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}