{"id":2606,"date":"2015-06-10T06:34:47","date_gmt":"2015-06-10T05:34:47","guid":{"rendered":"http:\/\/www.anadess.com\/blog\/?p=2606"},"modified":"2022-08-27T12:34:56","modified_gmt":"2022-08-27T11:34:56","slug":"quechua-ana-dess-se-plie-en-4-2","status":"publish","type":"post","link":"https:\/\/www.anadess.com\/blog\/quechua-ana-dess-se-plie-en-4-2\/","title":{"rendered":"Quechua"},"content":{"rendered":"<p>Cette semaine, Ana Dess se bat contre une tente Quechua&#8230; !<\/p>\n<p><a href=\"http:\/\/www.anadess.com\/blog\/wp-content\/uploads\/2015\/06\/Quechua-WEB.jpg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1500\" height=\"393\" class=\"alignnone size-full wp-image-2607\" src=\"http:\/\/www.anadess.com\/blog\/wp-content\/uploads\/2015\/06\/Quechua-WEB.jpg\" alt=\"Quechua-WEB\" srcset=\"https:\/\/www.anadess.com\/blog\/wp-content\/uploads\/2015\/06\/Quechua-WEB.jpg 1500w, https:\/\/www.anadess.com\/blog\/wp-content\/uploads\/2015\/06\/Quechua-WEB-300x79.jpg 300w, https:\/\/www.anadess.com\/blog\/wp-content\/uploads\/2015\/06\/Quechua-WEB-1024x268.jpg 1024w, https:\/\/www.anadess.com\/blog\/wp-content\/uploads\/2015\/06\/Quechua-WEB-600x157.jpg 600w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cette semaine, Ana Dess se bat contre une tente Quechua&#8230; !<\/p>\n","protected":false},"author":1,"featured_media":2607,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[3617],"tags":[2002,252,18,20,413,214,1131,22,23,1997,2001,1313,52,2003,58,963,1999,354,2000],"class_list":{"0":"post-2606","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-adp4-tome2","8":"tag-2-secondes","9":"tag-4-cases","10":"tag-ana-dess-2","11":"tag-anadess","12":"tag-anna","13":"tag-anna-dess","14":"tag-annadess","15":"tag-bande-dessinee","16":"tag-bd","17":"tag-cases","18":"tag-decathlon","19":"tag-envol","20":"tag-humour","21":"tag-kamicases","22":"tag-lyon","23":"tag-montseveroux","24":"tag-quechua","25":"tag-strip","26":"tag-tente"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quechua -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.anadess.com\/blog\/quechua-ana-dess-se-plie-en-4-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quechua -\" \/>\n<meta property=\"og:description\" content=\"Cette semaine, Ana Dess se bat contre une tente Quechua&#8230; !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.anadess.com\/blog\/quechua-ana-dess-se-plie-en-4-2\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-10T05:34:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-27T11:34:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.anadess.com\/blog\/wp-content\/uploads\/2015\/06\/Quechua-WEB.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"393\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"anadess\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"anadess\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/quechua-ana-dess-se-plie-en-4-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/quechua-ana-dess-se-plie-en-4-2\\\/\"},\"author\":{\"name\":\"anadess\",\"@id\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/#\\\/schema\\\/person\\\/bb444ea8b02863d199c15fb5e39d37fd\"},\"headline\":\"Quechua\",\"datePublished\":\"2015-06-10T05:34:47+00:00\",\"dateModified\":\"2022-08-27T11:34:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/quechua-ana-dess-se-plie-en-4-2\\\/\"},\"wordCount\":11,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/quechua-ana-dess-se-plie-en-4-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/Quechua-WEB.jpg\",\"keywords\":[\"2 secondes\",\"4 cases\",\"Ana Dess\",\"anadess\",\"anna\",\"anna dess\",\"annadess\",\"bande dessin\u00e9e\",\"BD\",\"cases\",\"decathlon\",\"envol\",\"humour\",\"kamicases\",\"lyon\",\"montseveroux\",\"quechua\",\"strip\",\"tente\"],\"articleSection\":[\"ADP4-Tome2\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.anadess.com\\\/blog\\\/quechua-ana-dess-se-plie-en-4-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/quechua-ana-dess-se-plie-en-4-2\\\/\",\"url\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/quechua-ana-dess-se-plie-en-4-2\\\/\",\"name\":\"Quechua -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/quechua-ana-dess-se-plie-en-4-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/quechua-ana-dess-se-plie-en-4-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/Quechua-WEB.jpg\",\"datePublished\":\"2015-06-10T05:34:47+00:00\",\"dateModified\":\"2022-08-27T11:34:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/#\\\/schema\\\/person\\\/bb444ea8b02863d199c15fb5e39d37fd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/quechua-ana-dess-se-plie-en-4-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.anadess.com\\\/blog\\\/quechua-ana-dess-se-plie-en-4-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/quechua-ana-dess-se-plie-en-4-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/Quechua-WEB.jpg\",\"contentUrl\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/Quechua-WEB.jpg\",\"width\":1500,\"height\":393},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/quechua-ana-dess-se-plie-en-4-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quechua\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/#\\\/schema\\\/person\\\/bb444ea8b02863d199c15fb5e39d37fd\",\"name\":\"anadess\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90504ecfdcd3e11ac8f9e24aa29999a71fc763be940051d5f20c6402abf281ac?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90504ecfdcd3e11ac8f9e24aa29999a71fc763be940051d5f20c6402abf281ac?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90504ecfdcd3e11ac8f9e24aa29999a71fc763be940051d5f20c6402abf281ac?s=96&d=mm&r=g\",\"caption\":\"anadess\"},\"url\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/author\\\/anadess\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quechua -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.anadess.com\/blog\/quechua-ana-dess-se-plie-en-4-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Quechua -","og_description":"Cette semaine, Ana Dess se bat contre une tente Quechua&#8230; !","og_url":"https:\/\/www.anadess.com\/blog\/quechua-ana-dess-se-plie-en-4-2\/","article_published_time":"2015-06-10T05:34:47+00:00","article_modified_time":"2022-08-27T11:34:56+00:00","og_image":[{"width":1500,"height":393,"url":"https:\/\/www.anadess.com\/blog\/wp-content\/uploads\/2015\/06\/Quechua-WEB.jpg","type":"image\/jpeg"}],"author":"anadess","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"anadess","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.anadess.com\/blog\/quechua-ana-dess-se-plie-en-4-2\/#article","isPartOf":{"@id":"https:\/\/www.anadess.com\/blog\/quechua-ana-dess-se-plie-en-4-2\/"},"author":{"name":"anadess","@id":"https:\/\/www.anadess.com\/blog\/#\/schema\/person\/bb444ea8b02863d199c15fb5e39d37fd"},"headline":"Quechua","datePublished":"2015-06-10T05:34:47+00:00","dateModified":"2022-08-27T11:34:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.anadess.com\/blog\/quechua-ana-dess-se-plie-en-4-2\/"},"wordCount":11,"commentCount":0,"image":{"@id":"https:\/\/www.anadess.com\/blog\/quechua-ana-dess-se-plie-en-4-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.anadess.com\/blog\/wp-content\/uploads\/2015\/06\/Quechua-WEB.jpg","keywords":["2 secondes","4 cases","Ana Dess","anadess","anna","anna dess","annadess","bande dessin\u00e9e","BD","cases","decathlon","envol","humour","kamicases","lyon","montseveroux","quechua","strip","tente"],"articleSection":["ADP4-Tome2"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.anadess.com\/blog\/quechua-ana-dess-se-plie-en-4-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.anadess.com\/blog\/quechua-ana-dess-se-plie-en-4-2\/","url":"https:\/\/www.anadess.com\/blog\/quechua-ana-dess-se-plie-en-4-2\/","name":"Quechua -","isPartOf":{"@id":"https:\/\/www.anadess.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.anadess.com\/blog\/quechua-ana-dess-se-plie-en-4-2\/#primaryimage"},"image":{"@id":"https:\/\/www.anadess.com\/blog\/quechua-ana-dess-se-plie-en-4-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.anadess.com\/blog\/wp-content\/uploads\/2015\/06\/Quechua-WEB.jpg","datePublished":"2015-06-10T05:34:47+00:00","dateModified":"2022-08-27T11:34:56+00:00","author":{"@id":"https:\/\/www.anadess.com\/blog\/#\/schema\/person\/bb444ea8b02863d199c15fb5e39d37fd"},"breadcrumb":{"@id":"https:\/\/www.anadess.com\/blog\/quechua-ana-dess-se-plie-en-4-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.anadess.com\/blog\/quechua-ana-dess-se-plie-en-4-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.anadess.com\/blog\/quechua-ana-dess-se-plie-en-4-2\/#primaryimage","url":"https:\/\/www.anadess.com\/blog\/wp-content\/uploads\/2015\/06\/Quechua-WEB.jpg","contentUrl":"https:\/\/www.anadess.com\/blog\/wp-content\/uploads\/2015\/06\/Quechua-WEB.jpg","width":1500,"height":393},{"@type":"BreadcrumbList","@id":"https:\/\/www.anadess.com\/blog\/quechua-ana-dess-se-plie-en-4-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.anadess.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Quechua"}]},{"@type":"WebSite","@id":"https:\/\/www.anadess.com\/blog\/#website","url":"https:\/\/www.anadess.com\/blog\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.anadess.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.anadess.com\/blog\/#\/schema\/person\/bb444ea8b02863d199c15fb5e39d37fd","name":"anadess","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/90504ecfdcd3e11ac8f9e24aa29999a71fc763be940051d5f20c6402abf281ac?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/90504ecfdcd3e11ac8f9e24aa29999a71fc763be940051d5f20c6402abf281ac?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/90504ecfdcd3e11ac8f9e24aa29999a71fc763be940051d5f20c6402abf281ac?s=96&d=mm&r=g","caption":"anadess"},"url":"https:\/\/www.anadess.com\/blog\/author\/anadess\/"}]}},"_links":{"self":[{"href":"https:\/\/www.anadess.com\/blog\/wp-json\/wp\/v2\/posts\/2606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.anadess.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.anadess.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.anadess.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.anadess.com\/blog\/wp-json\/wp\/v2\/comments?post=2606"}],"version-history":[{"count":2,"href":"https:\/\/www.anadess.com\/blog\/wp-json\/wp\/v2\/posts\/2606\/revisions"}],"predecessor-version":[{"id":14934,"href":"https:\/\/www.anadess.com\/blog\/wp-json\/wp\/v2\/posts\/2606\/revisions\/14934"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.anadess.com\/blog\/wp-json\/wp\/v2\/media\/2607"}],"wp:attachment":[{"href":"https:\/\/www.anadess.com\/blog\/wp-json\/wp\/v2\/media?parent=2606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.anadess.com\/blog\/wp-json\/wp\/v2\/categories?post=2606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.anadess.com\/blog\/wp-json\/wp\/v2\/tags?post=2606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}