{"id":3395,"date":"2017-04-05T12:33:40","date_gmt":"2017-04-05T11:33:40","guid":{"rendered":"http:\/\/www.anadess.com\/blog\/?p=3395"},"modified":"2022-08-24T19:44:24","modified_gmt":"2022-08-24T18:44:24","slug":"voyage-sous-le-soleil-de-crete","status":"publish","type":"post","link":"https:\/\/www.anadess.com\/blog\/voyage-sous-le-soleil-de-crete\/","title":{"rendered":"Voyage sous le soleil de Cr\u00e8te"},"content":{"rendered":"<p><a href=\"http:\/\/www.anadess.com\/blog\/wp-content\/uploads\/2017\/04\/Crete-WEB.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-3396 size-full\" src=\"http:\/\/www.anadess.com\/blog\/wp-content\/uploads\/2017\/04\/Crete-WEB.jpg\" alt=\"\" width=\"1500\" height=\"393\" srcset=\"https:\/\/www.anadess.com\/blog\/wp-content\/uploads\/2017\/04\/Crete-WEB.jpg 1500w, https:\/\/www.anadess.com\/blog\/wp-content\/uploads\/2017\/04\/Crete-WEB-300x79.jpg 300w, https:\/\/www.anadess.com\/blog\/wp-content\/uploads\/2017\/04\/Crete-WEB-768x201.jpg 768w, https:\/\/www.anadess.com\/blog\/wp-content\/uploads\/2017\/04\/Crete-WEB-1024x268.jpg 1024w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/><\/a><\/p>\n<p><strong>La Cr\u00e8te<\/strong>&#8230; cette \u00eele sauvage, rocailleuse, balay\u00e9e par les vents chauds, endormie sous le soleil de plomb abrite des merveilles insoup\u00e7onn\u00e9es. Ce n\u2019est pas une destination que j\u2019ai choisie, mais pourtant, elle m\u2019attendait.<\/p>\n<p>Chaque matin c\u2019est un festival du go\u00fbt : orange, citron,&nbsp;figue,&nbsp;tomate,&nbsp;f\u00eata,&nbsp;concombre\u2026 Du soleil en bouche,<strong>&nbsp;le paradis des v\u00e9g\u00e9tariens<\/strong>&nbsp;! Je crois que je pourrais manger des salades cr\u00e9toises tous les jours de ma vie. L\u2019huile d\u2019olive&nbsp;est un d\u00e9lice, et je la savoure avec un morceau de pain.<\/p>\n<p>Au coeur de ce petit village perch\u00e9 dans les champs d\u2019oliviers,&nbsp;<strong>je marche seule au milieu du temps<\/strong>. L\u2019Histoire c\u00f4toie le pr\u00e9sent, des chapelles toutes blanches semblent avoir travers\u00e9es les \u00e2ges. Les anciens assis sur leurs chaises dehors regardent la vie.&nbsp;Je continue \u00e0 marcher, et je finis par me perdre au milieu des oliviers.<\/p>\n<p>Si majestueux, certains sont l\u00e0 depuis des mill\u00e9naires. Leurs troncs tortueux sont marqu\u00e9s de rides, j\u2019imagine alors tout ce qu\u2019ils ont d\u00fb voir et entendre. Je pose ma couverture et me couche au pied de l\u2019un d\u2019eux, je ne dois pas \u00eatre la premi\u00e8re \u00e0 faire la sieste sous celui-ci.&nbsp;C\u2019est un instant sacr\u00e9, la sieste. Tout est ferm\u00e9 jusqu\u2019\u00e0 16h, le temps se suspend et j\u2019en profite pour faire pause.<\/p>\n<p>Sur la&nbsp;plage&nbsp;que j\u2019ai choisie, galets, rochers et sables se partagent le paysage. Il existe 1001 plages en Cr\u00e8te et si vous choisissez avec soin, il n\u2019y aura personne ! Je m\u2019\u00e9quipe :&nbsp;masque, tuba, palmes. C\u2019est parti pour la d\u00e9couverte des fonds marins. Je ne fais pas 1 m\u00e8tre que d\u00e9j\u00e0 je peux observer les poissons. L\u2019eau est limpide. La fin de journ\u00e9e me r\u00e9v\u00e8le une cavit\u00e9 \u00e0 la surface de l\u2019eau. Je m\u2019y engouffre, j\u2019ai pied, j\u2019enl\u00e8ve mon masque, je l\u00e8ve la t\u00eate et&nbsp;<strong>OH SURPRISE : des dizaines de chauves-souris dorment<\/strong>. Je claque des mains et je les regardent voler, quelle magie ! Un moment unique, comme un secret.<\/p>\n<p>Mais que serait la Cr\u00e8te, berceau de l\u2019histoire occidental sans ses sites historiques ?<br \/>\nJ\u2019ai travers\u00e9 les Gorges de Samaria (les gorges les plus impressionnantes d\u2019Europe), fl\u00e2n\u00e9 dans Hania, belle cit\u00e9 v\u00e9nitienne, parcouru les collines arides en pensant \u00e0 Minos (n\u00e9 en Cr\u00e8te dans la mythologie)\u2026<br \/>\nEt pour terminer j\u2019ai visit\u00e9 le magnifique mus\u00e9e arch\u00e9ologique d\u2019Heraklion, et croyez-moi il en vaut le d\u00e9tour !<\/p>\n<p>Au del\u00e0 de la chaleur du soleil, j\u2019ai trouv\u00e9 les plus beaux sourires, l\u2019hospitalit\u00e9 et j\u2019ai pu ressentir une partie de notre Histoire. Une exp\u00e9rience riche en \u00e9motions. Vive le raki, la past\u00e8que et les cigales !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Cr\u00e8te&#8230; cette \u00eele sauvage, rocailleuse, balay\u00e9e par les vents chauds, endormie sous le soleil de plomb abrite des merveilles insoup\u00e7onn\u00e9es. Ce n\u2019est pas une destination que j\u2019ai choisie, mais&hellip;<\/p>\n<p> <a class=\"more-link\" href=\"https:\/\/www.anadess.com\/blog\/voyage-sous-le-soleil-de-crete\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":1,"featured_media":3396,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1213],"tags":[18,20,214,2130,2668,22,23,2515,2663,2660,34,2664,619,2666,2667,2661,247,2669,963,2591,2670,2665,1992,155,2662,1233],"class_list":{"0":"post-3395","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-voyages","8":"tag-ana-dess-2","9":"tag-anadess","10":"tag-anna-dess","11":"tag-aquarelle","12":"tag-archeologie","13":"tag-bande-dessinee","14":"tag-bd","15":"tag-carnet-de-voyage","16":"tag-concombre","17":"tag-crete","18":"tag-dessin","19":"tag-feta","20":"tag-grece","21":"tag-hania","22":"tag-heraklion","23":"tag-ile","24":"tag-illustrations","25":"tag-minos","26":"tag-montseveroux","27":"tag-mythologie","28":"tag-raki","29":"tag-samaria","30":"tag-soleil","31":"tag-sud","32":"tag-veretarien","33":"tag-voyage"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Voyage sous le soleil de Cr\u00e8te -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.anadess.com\/blog\/voyage-sous-le-soleil-de-crete\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Voyage sous le soleil de Cr\u00e8te -\" \/>\n<meta property=\"og:description\" content=\"La Cr\u00e8te&#8230; cette \u00eele sauvage, rocailleuse, balay\u00e9e par les vents chauds, endormie sous le soleil de plomb abrite des merveilles insoup\u00e7onn\u00e9es. Ce n\u2019est pas une destination que j\u2019ai choisie, mais&hellip;  Lire la suite\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.anadess.com\/blog\/voyage-sous-le-soleil-de-crete\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-05T11:33:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-24T18:44:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.anadess.com\/blog\/wp-content\/uploads\/2017\/04\/Crete-WEB.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"393\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"anadess\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"anadess\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/voyage-sous-le-soleil-de-crete\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/voyage-sous-le-soleil-de-crete\\\/\"},\"author\":{\"name\":\"anadess\",\"@id\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/#\\\/schema\\\/person\\\/bb444ea8b02863d199c15fb5e39d37fd\"},\"headline\":\"Voyage sous le soleil de Cr\u00e8te\",\"datePublished\":\"2017-04-05T11:33:40+00:00\",\"dateModified\":\"2022-08-24T18:44:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/voyage-sous-le-soleil-de-crete\\\/\"},\"wordCount\":497,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/voyage-sous-le-soleil-de-crete\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Crete-WEB.jpg\",\"keywords\":[\"Ana Dess\",\"anadess\",\"anna dess\",\"aquarelle\",\"arch\u00e9ologie\",\"bande dessin\u00e9e\",\"BD\",\"carnet de voyage\",\"concombre\",\"cr\u00e8te\",\"dessin\",\"feta\",\"gr\u00e8ce\",\"hania\",\"Heraklion\",\"\u00eele\",\"illustrations\",\"minos\",\"montseveroux\",\"mythologie\",\"raki\",\"Samaria\",\"soleil\",\"SUD\",\"v\u00e9r\u00e9tarien\",\"voyage\"],\"articleSection\":[\"Voyages\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.anadess.com\\\/blog\\\/voyage-sous-le-soleil-de-crete\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/voyage-sous-le-soleil-de-crete\\\/\",\"url\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/voyage-sous-le-soleil-de-crete\\\/\",\"name\":\"Voyage sous le soleil de Cr\u00e8te -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/voyage-sous-le-soleil-de-crete\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/voyage-sous-le-soleil-de-crete\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Crete-WEB.jpg\",\"datePublished\":\"2017-04-05T11:33:40+00:00\",\"dateModified\":\"2022-08-24T18:44:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/#\\\/schema\\\/person\\\/bb444ea8b02863d199c15fb5e39d37fd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/voyage-sous-le-soleil-de-crete\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.anadess.com\\\/blog\\\/voyage-sous-le-soleil-de-crete\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/voyage-sous-le-soleil-de-crete\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Crete-WEB.jpg\",\"contentUrl\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Crete-WEB.jpg\",\"width\":1500,\"height\":393},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/voyage-sous-le-soleil-de-crete\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Voyage sous le soleil de Cr\u00e8te\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/#\\\/schema\\\/person\\\/bb444ea8b02863d199c15fb5e39d37fd\",\"name\":\"anadess\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90504ecfdcd3e11ac8f9e24aa29999a71fc763be940051d5f20c6402abf281ac?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90504ecfdcd3e11ac8f9e24aa29999a71fc763be940051d5f20c6402abf281ac?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90504ecfdcd3e11ac8f9e24aa29999a71fc763be940051d5f20c6402abf281ac?s=96&d=mm&r=g\",\"caption\":\"anadess\"},\"url\":\"https:\\\/\\\/www.anadess.com\\\/blog\\\/author\\\/anadess\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Voyage sous le soleil de Cr\u00e8te -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.anadess.com\/blog\/voyage-sous-le-soleil-de-crete\/","og_locale":"fr_FR","og_type":"article","og_title":"Voyage sous le soleil de Cr\u00e8te -","og_description":"La Cr\u00e8te&#8230; cette \u00eele sauvage, rocailleuse, balay\u00e9e par les vents chauds, endormie sous le soleil de plomb abrite des merveilles insoup\u00e7onn\u00e9es. Ce n\u2019est pas une destination que j\u2019ai choisie, mais&hellip;  Lire la suite","og_url":"https:\/\/www.anadess.com\/blog\/voyage-sous-le-soleil-de-crete\/","article_published_time":"2017-04-05T11:33:40+00:00","article_modified_time":"2022-08-24T18:44:24+00:00","og_image":[{"width":1500,"height":393,"url":"https:\/\/www.anadess.com\/blog\/wp-content\/uploads\/2017\/04\/Crete-WEB.jpg","type":"image\/jpeg"}],"author":"anadess","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"anadess","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.anadess.com\/blog\/voyage-sous-le-soleil-de-crete\/#article","isPartOf":{"@id":"https:\/\/www.anadess.com\/blog\/voyage-sous-le-soleil-de-crete\/"},"author":{"name":"anadess","@id":"https:\/\/www.anadess.com\/blog\/#\/schema\/person\/bb444ea8b02863d199c15fb5e39d37fd"},"headline":"Voyage sous le soleil de Cr\u00e8te","datePublished":"2017-04-05T11:33:40+00:00","dateModified":"2022-08-24T18:44:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.anadess.com\/blog\/voyage-sous-le-soleil-de-crete\/"},"wordCount":497,"commentCount":0,"image":{"@id":"https:\/\/www.anadess.com\/blog\/voyage-sous-le-soleil-de-crete\/#primaryimage"},"thumbnailUrl":"https:\/\/www.anadess.com\/blog\/wp-content\/uploads\/2017\/04\/Crete-WEB.jpg","keywords":["Ana Dess","anadess","anna dess","aquarelle","arch\u00e9ologie","bande dessin\u00e9e","BD","carnet de voyage","concombre","cr\u00e8te","dessin","feta","gr\u00e8ce","hania","Heraklion","\u00eele","illustrations","minos","montseveroux","mythologie","raki","Samaria","soleil","SUD","v\u00e9r\u00e9tarien","voyage"],"articleSection":["Voyages"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.anadess.com\/blog\/voyage-sous-le-soleil-de-crete\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.anadess.com\/blog\/voyage-sous-le-soleil-de-crete\/","url":"https:\/\/www.anadess.com\/blog\/voyage-sous-le-soleil-de-crete\/","name":"Voyage sous le soleil de Cr\u00e8te -","isPartOf":{"@id":"https:\/\/www.anadess.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.anadess.com\/blog\/voyage-sous-le-soleil-de-crete\/#primaryimage"},"image":{"@id":"https:\/\/www.anadess.com\/blog\/voyage-sous-le-soleil-de-crete\/#primaryimage"},"thumbnailUrl":"https:\/\/www.anadess.com\/blog\/wp-content\/uploads\/2017\/04\/Crete-WEB.jpg","datePublished":"2017-04-05T11:33:40+00:00","dateModified":"2022-08-24T18:44:24+00:00","author":{"@id":"https:\/\/www.anadess.com\/blog\/#\/schema\/person\/bb444ea8b02863d199c15fb5e39d37fd"},"breadcrumb":{"@id":"https:\/\/www.anadess.com\/blog\/voyage-sous-le-soleil-de-crete\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.anadess.com\/blog\/voyage-sous-le-soleil-de-crete\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.anadess.com\/blog\/voyage-sous-le-soleil-de-crete\/#primaryimage","url":"https:\/\/www.anadess.com\/blog\/wp-content\/uploads\/2017\/04\/Crete-WEB.jpg","contentUrl":"https:\/\/www.anadess.com\/blog\/wp-content\/uploads\/2017\/04\/Crete-WEB.jpg","width":1500,"height":393},{"@type":"BreadcrumbList","@id":"https:\/\/www.anadess.com\/blog\/voyage-sous-le-soleil-de-crete\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.anadess.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Voyage sous le soleil de Cr\u00e8te"}]},{"@type":"WebSite","@id":"https:\/\/www.anadess.com\/blog\/#website","url":"https:\/\/www.anadess.com\/blog\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.anadess.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.anadess.com\/blog\/#\/schema\/person\/bb444ea8b02863d199c15fb5e39d37fd","name":"anadess","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/90504ecfdcd3e11ac8f9e24aa29999a71fc763be940051d5f20c6402abf281ac?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/90504ecfdcd3e11ac8f9e24aa29999a71fc763be940051d5f20c6402abf281ac?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/90504ecfdcd3e11ac8f9e24aa29999a71fc763be940051d5f20c6402abf281ac?s=96&d=mm&r=g","caption":"anadess"},"url":"https:\/\/www.anadess.com\/blog\/author\/anadess\/"}]}},"_links":{"self":[{"href":"https:\/\/www.anadess.com\/blog\/wp-json\/wp\/v2\/posts\/3395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.anadess.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.anadess.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.anadess.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.anadess.com\/blog\/wp-json\/wp\/v2\/comments?post=3395"}],"version-history":[{"count":2,"href":"https:\/\/www.anadess.com\/blog\/wp-json\/wp\/v2\/posts\/3395\/revisions"}],"predecessor-version":[{"id":14836,"href":"https:\/\/www.anadess.com\/blog\/wp-json\/wp\/v2\/posts\/3395\/revisions\/14836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.anadess.com\/blog\/wp-json\/wp\/v2\/media\/3396"}],"wp:attachment":[{"href":"https:\/\/www.anadess.com\/blog\/wp-json\/wp\/v2\/media?parent=3395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.anadess.com\/blog\/wp-json\/wp\/v2\/categories?post=3395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.anadess.com\/blog\/wp-json\/wp\/v2\/tags?post=3395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}